{"id":10397,"date":"2024-02-13T12:51:53","date_gmt":"2024-02-13T11:51:53","guid":{"rendered":"https:\/\/clinicasden.com\/politica-de-cookies\/"},"modified":"2025-10-25T14:43:56","modified_gmt":"2025-10-25T12:43:56","slug":"politica-cookies","status":"publish","type":"page","link":"https:\/\/clinicasden.com\/ca\/politica-cookies\/","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_single_image image=\u00bb2741&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb qode_css_animation=\u00bb\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][vc_empty_space height=\u00bb50px\u00bb][vc_column_text]<\/p>\n<h1>Pol\u00edtica de Cookies<\/h1>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb50px\u00bb][vc_column_text]<span style=\"font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-3); color: var(--ast-global-color-1);\">En cumplimiento con lo dispuesto en el art\u00edculo 22.2 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico, <strong>ORTHO DOCTORS S.L.P.<\/strong> (en adelante, el titular), titular del website <a href=\"https:\/\/clinicasden.com\">clinicasden.com <\/a><\/span><span style=\"font-style: inherit; font-weight: inherit; background-color: var(--ast-global-color-3); color: var(--ast-global-color-1);\">(en adelante, el website) le informa en esta secci\u00f3n la pol\u00edtica de recogida y tratamiento de cookies propias y terceros, as\u00ed como sus finalidades y plazos.<\/span><\/p>\n<h2>\u00bfQu\u00e9 son las cookies?<\/h2>\n<p>Las cookies son peque\u00f1os archivos de texto que las p\u00e1ginas web almacenan en el navegador del usuario que las visita para hacer m\u00e1s eficiente la experiencia del usuario.<\/p>\n<p>Este sitio web utiliza cookies y\/o tecnolog\u00edas similares que almacenan y recuperan informaci\u00f3n cuando navegas. En general, estas tecnolog\u00edas pueden servir para finalidades muy diversas, como, por ejemplo, reconocerte como usuario, obtener informaci\u00f3n sobre tus h\u00e1bitos de navegaci\u00f3n, o personalizar la forma en que se muestra el contenido. Los usos concretos que hacemos de estas tecnolog\u00edas se describen a continuaci\u00f3n.<\/p>\n<p>Esta p\u00e1gina web utiliza cookies propias y de terceros para personalizar el contenido y los anuncios, ofrecer funciones de redes sociales y analizar el tr\u00e1fico. Adem\u00e1s, compartimos informaci\u00f3n sobre el uso que haga del sitio web con nuestros partners de redes sociales, publicidad y an\u00e1lisis web, quienes pueden combinarla con otra informaci\u00f3n que les haya proporcionado o que hayan recopilado a partir del uso que haya hecho de sus servicios.<\/p>\n<p>Algunas cookies son esenciales para el funcionamiento del sitio, por ejemplo, el buscador incorporado. Otras se usan para para recopilar informaci\u00f3n con fines estad\u00edsticos y de uso de la web.<\/p>\n<h2>Uso de cookies seg\u00fan la gesti\u00f3n y el tiempo activas<\/h2>\n<p>Esta p\u00e1gina web utiliza servicios de terceros para recopilar informaci\u00f3n con fines estad\u00edsticos y de uso de la web. En concreto, Cookies propias, Cookies de terceros, de sesi\u00f3n y activas para fines de An\u00e1lisis, de Marketing y T\u00e9cnicos.<\/p>\n<p>La siguiente informaci\u00f3n de los tipos de cookies que contiene esta p\u00e1gina ayuda a comprender mejor las funciones que hacen posible.<\/p>\n<p>Seg\u00fan el tiempo de permanencia en el navegador, se dividen en:<\/p>\n<ul>\n<li><strong>Cookies de sesi\u00f3n:<\/strong> Son cookies temporales que permanecen en el espacio de cookies de su equipo hasta que cierra el navegador, por lo que ninguna queda registrada en el disco del usuario. La informaci\u00f3n obtenida por medio de estas cookies sirve para hacer posible la gesti\u00f3n operativa con cada uno de los usuarios que est\u00e1 accediendo de forma simult\u00e1nea a la web.<\/li>\n<li><strong>Cookies persistentes:<\/strong> Son cookies que permanecen almacenadas en el espacio de cookies de su equipo una vez cerrado el navegador, y que volver\u00e1 a consultar dicha p\u00e1gina web la pr\u00f3xima vez que acceda a ella para recordar informaci\u00f3n que facilite la navegaci\u00f3n (acceder directamente al servicio sin necesidad de hacer el proceso de login) o la prestaci\u00f3n de un servicio comercial (ofrecer aquellos productos o servicios relacionados con anteriores visitas).<\/li>\n<\/ul>\n<p>Adem\u00e1s, las cookies intercambiadas al navegar por una p\u00e1gina web pueden ser:<\/p>\n<ul>\n<li><strong>Cookies de origen o propias:<\/strong> Son cookies generadas por la propia p\u00e1gina web que se est\u00e1 visitando.<\/li>\n<li><strong>Cookies de terceros:<\/strong> Son cookies que se reciben al navegar por esa p\u00e1gina web, pero que han sido generadas por un tercer servicio que se encuentra hospedado en ella. Un ejemplo puede ser la cookie empleada por un anuncio o banner de publicidad que se encuentra en la p\u00e1gina web que visitamos. Otro puede ser la cookie empleada por un contador de visitantes contratado por la p\u00e1gina web que visitamos.<\/li>\n<\/ul>\n<h2>\u00bfPara qu\u00e9 utiliza las cookies esta p\u00e1gina web?<\/h2>\n<p>Esta p\u00e1gina web utiliza las cookies para una serie de finalidades, incluidas:<\/p>\n<ul>\n<li><strong>Necesarias o t\u00e9cnicas<\/strong>: son aquellas que permiten al usuario la navegacio\u0301n a trave\u0301s de una pa\u0301gina web, plataforma o aplicacio\u0301n y la utilizacio\u0301n de las diferentes opciones o servicios que en ella existan, incluyendo aquellas que el editor utiliza para permitir la gestio\u0301n y operativa de la pa\u0301gina web y habilitar sus funciones y servicios.<\/li>\n<li><strong>Estad\u00edsticas o de an\u00e1lisis o medici\u00f3n<\/strong>: son aquellas que, tratadas por nosotros o por terceros, nos permiten cuantificar el n\u00famero de usuarios y as\u00ed realizar la medici\u00f3n y an\u00e1lisis estad\u00edstico de la utilizaci\u00f3n que hacen los usuarios del servicio ofertado. Para ello se analiza su navegaci\u00f3n en nuestra p\u00e1gina web con el fin de mejorar la oferta de productos o servicios que le ofrecemos.<\/li>\n<li><strong>Publicitarias comportamentales o de marketing<\/strong>: son aquellas que, tratadas por nosotros o por terceros, permiten analizar sus h\u00e1bitos de navegaci\u00f3n en Internet para mostrarle publicidad relacionada con su perfil de navegaci\u00f3n.<\/li>\n<li><strong>De preferencias o personalizaci\u00f3n<\/strong>: Las cookies de preferencias permiten a la p\u00e1gina web recordar informaci\u00f3n que cambia la forma en que la p\u00e1gina se comporta o el aspecto que tiene, como su idioma preferido o la regi\u00f3n en la que usted se encuentra.<\/li>\n<\/ul>\n<p>Las cookies de este sitio web se usan para personalizar el contenido y los anuncios, ofrecer funciones de redes sociales y analizar el tr\u00e1fico.<\/p>\n<p>Adem\u00e1s, compartimos informaci\u00f3n sobre el uso que haga del sitio web con nuestros partners de redes sociales, publicidad y an\u00e1lisis web, quienes pueden combinarla con otra informaci\u00f3n que les haya proporcionado o que hayan recopilado a partir del uso que haya hecho de sus servicios.<\/p>\n<p>La ley afirma que podemos almacenar cookies en su dispositivo si son estrictamente necesarias para el funcionamiento de esta p\u00e1gina. Para todos los dem\u00e1s tipos de cookies necesitamos su permiso.<\/p>\n<p>Esta p\u00e1gina utiliza tipos diferentes de cookies. Algunas cookies son colocadas por servicios de terceros que aparecen en nuestras p\u00e1ginas.<\/p>\n<p>En cualquier momento puede cambiar o retirar su consentimiento desde la Declaraci\u00f3n de cookies en nuestro sitio web.<\/p>\n<p>Obtenga m\u00e1s informaci\u00f3n sobre qui\u00e9nes somos, c\u00f3mo puede contactarnos y c\u00f3mo procesamos los datos personales en nuestra <a href=\"\/politica-privacidad\/\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de privacidad<\/a>.<\/p>\n<p>Al contactarnos respecto a su consentimiento, por favor, indique el ID y la fecha de su consentimiento.<\/p>\n<div id=\"cmplz-manage-consent-container-nojavascript\">Heu carregat la Pol\u00edtica de galetes sense suport javascript.&nbsp;A AMP, podeu utilitzar el bot\u00f3 de gesti\u00f3 del consentiment a la part inferior de la p\u00e0gina.<\/div><div id=\"cmplz-manage-consent-container\" name=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div>\n<h2>Cookies usadas en este sitio<\/h2>\n<div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem WordPress per a desenvolupament del lloc web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\" aria-label=\"Read more about WordPress service on Cookie Database\">Read more about WordPress<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wpemojisettingssupports\/\">wpEmojiSettingsSupports<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">sessi\u00f3<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema els detalls del navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Read if cookies can be placed<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store logged in users<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>PixelYourSite<\/h3>\n\t\t<p>Estad\u00edstiques<\/p>\n\t\t<label for=\"cmplz_service_pixelyoursite\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service pixelyoursite<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_pixelyoursite\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"pixelyoursite\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p> <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/pixelyoursite\/\" aria-label=\"Read more about PixelYourSite service on Cookie Database\">Read more about PixelYourSite<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edstiques<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/pixelyoursite\/pystrafficsource\/\">pysTrafficSource<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">1 dia<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema el lloc web de refer\u00e8ncia<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/pixelyoursite\/pys_landing_page\/\">pys_landing_page<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">sessi\u00f3<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzemeu quina p\u00e0gina es va visitar primer<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Adsense<\/h3>\n\t\t<p>M\u00e0rqueting<\/p>\n\t\t<label for=\"cmplz_service_google-adsense\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-adsense<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-adsense\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-adsense\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem Google Adsense per a mostrar publicitat. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-adsense\/\" aria-label=\"Read more about Google Adsense service on Cookie Database\">Read more about Google Adsense<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Per a m\u00e9s informaci\u00f3, llegiu si us plau la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacitat de Google Adsense<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>M\u00e0rqueting<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-adsense\/_gcl_au\/\">_gcl_au<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store and track conversions<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-adsense\/google_adsense_settings\/\">google_adsense_settings<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Activeu la publicaci\u00f3 d&#039;anuncios o retargeting<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>GDPR Cookie Consent<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_gdpr-cookie-consent\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service gdpr-cookie-consent<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_gdpr-cookie-consent\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"gdpr-cookie-consent\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem GDPR Cookie Consent per a gesti\u00f3 del consentiment de cookies. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/gdpr-cookie-consent\/\" aria-label=\"Read more about GDPR Cookie Consent service on Cookie Database\">Read more about GDPR Cookie Consent<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/gdpr-cookie-consent\/viewed_cookie_policy\/\">viewed_cookie_policy<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema si s&#039;ha mostrat un missatge<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Estad\u00edstiques, Funcional<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem Google Analytics per a estad\u00edstiques del lloc web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-analytics\/\" aria-label=\"Read more about Google Analytics service on Cookie Database\">Read more about Google Analytics<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Per a m\u00e9s informaci\u00f3, llegiu si us plau la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacitat de Google Analytics<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Estad\u00edstiques<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_gid\/\">_gid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">1 day<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store and count pageviews<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga\/\">_ga<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">2 years<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store and count pageviews<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga_\/\">_ga_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store and count pageviews<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_gat_ua-2\/\">_gat_UA-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Provide technical monitoring<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>Funcional<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem WPML per a gesti\u00f3 local. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wpml\/\" aria-label=\"Read more about WPML service on Cookie Database\">Read more about WPML<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wpml\/wp-wpml_current_language\/\">wp-wpml_current_language<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">1 day<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store language settings<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Elementor<\/h3>\n\t\t<p>Statistics (anonymous)<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service elementor<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem Elementor per a creaci\u00f3 de contingut. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/elementor\/\" aria-label=\"Read more about Elementor service on Cookie Database\">Read more about Elementor<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Aquestes dades no es comparteixen amb tercers.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistics (anonymous)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/elementor\/elementor\/\">elementor<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store performed actions on the website<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>M\u00e0rqueting<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem Google Fonts per a visualitzaci\u00f3 de fonts web. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\" aria-label=\"Read more about Google Fonts service on Cookie Database\">Read more about Google Fonts<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Per a m\u00e9s informaci\u00f3, llegiu si us plau la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacitat de Google Fonts<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>M\u00e0rqueting<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-fonts\/tcb_google_fonts\/\">Google Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">no<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Preguntar la direcci\u00f3 IP de l&#039;usuari<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>M\u00e0rqueting<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem Google Maps per a visualitzaci\u00f3 de mapes. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-maps\/\" aria-label=\"Read more about Google Maps service on Cookie Database\">Read more about Google Maps<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Per a m\u00e9s informaci\u00f3, llegiu si us plau la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacitat de Google Maps<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>M\u00e0rqueting<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-maps\/google-maps-api\/\">Google Maps API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">no<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Preguntar la direcci\u00f3 IP de l&#039;usuari<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>M\u00e0rqueting<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem YouTube per a visualitzaci\u00f3 dels v\u00eddeos. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\" aria-label=\"Read more about YouTube service on Cookie Database\">Read more about YouTube<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Per a m\u00e9s informaci\u00f3, llegiu si us plau la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">pol\u00edtica de privacitat de YouTube<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>M\u00e0rqueting<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/gps\/\">GPS<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">sessi\u00f3<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema dades d\u2019ubicaci\u00f3<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/visitor_info1_live\/\">VISITOR_INFO1_LIVE<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">6 mesos<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Activeu la publicaci\u00f3 d&#039;anuncios o retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/ysc\/\">YSC<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">sessi\u00f3<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store and track interaction<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/pref\/\">PREF<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">8 mesos<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema les prefer\u00e8ncies de l&#039;usuari<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Facebook<\/h3>\n\t\t<p>M\u00e0rqueting, Funcional<\/p>\n\t\t<label for=\"cmplz_service_facebook\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service facebook<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_facebook\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"facebook\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p>Utilitzem Facebook per a visualitzaci\u00f3 de publicacions socials recents i\/o botons de compartici\u00f3 social. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/facebook\/\" aria-label=\"Read more about Facebook service on Cookie Database\">Read more about Facebook<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>Per a m\u00e9s informaci\u00f3, llegiu si us plau la <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/policy\/cookies\">pol\u00edtica de privacitat de Facebook<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>M\u00e0rqueting<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbc\/\">_fbc<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">2 anys<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema darrera visita<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fbm_\/\">fbm*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">1 any<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Guarda detalls del compte<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/xs\/\">xs<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">3 mesos<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema un identificador de sessi\u00f3 \u00fanica<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/fr\/\">fr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">3 mesos<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Activeu la publicaci\u00f3 d&#039;anuncios o retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/act\/\">act<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">90 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Mantenir els usuaris connectats<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbp\/\">_fbp<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">3 months<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Store and track visits across websites<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/datr\/\">datr<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">2 anys<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Proporcionar prevenci\u00f3 de fraus<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/c_user\/\">c_user<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">30 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema un identificador d&#039;usuari \u00fanic<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/sb\/\">sb<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">2 anys<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema els detalls del navegador<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/_fbm_\/\">*_fbm_<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">1 any<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Guarda detalls del compte<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funcional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/wd\/\">wd<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">1 semana<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Determina la resoluci\u00f3 de la pantalla<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/csm\/\">csm<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">90 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Proporcionar prevenci\u00f3 de fraus<\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/facebook\/actppresence\/\">actppresence<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">sessi\u00f3<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\">Emmagatzema i fa un seguiment si la pestanya del navegador est\u00e0 activa<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Diversos<\/h3>\n\t\t<p>Finalitat pendent d'investigaci\u00f3<\/p>\n\t\t<label for=\"cmplz_service_diversos\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service diversos<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_diversos\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"diversos\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>\u00das<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Compartint dades<\/h4>\n\t\t<p>L'intercanvi de dades est\u00e0 pendent d'investigaci\u00f3<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalitat pendent d'investigaci\u00f3<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">NRBA_SESSION<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">pbid<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/unknown-service\/cookielawinfo-checkbox\/\">cookielawinfo-checkbox-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">pys_first_visit<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">last_pysTrafficSource<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">pys_session_limit<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">pys_start_session<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">last_pys_landing_page<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rank-math-option-sitemap-index<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rank-math-option-titles-index<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">lastExternalReferrer<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">lastExternalReferrerTime<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_globals<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">e_kit-elements-defaults<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_grecaptcha<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rank-math-option-search-index<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">copiedShortcode<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">rank-math-option-general-index<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\">365 dies<\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-5wrdzcmj90<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">continueReview<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-krqb7ckugp<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-95z0cb0yxb<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-j042jylrre<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">persist:hs-beacon-44cc73fb-7636-4206-b115-c7b33823551b<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-803tlui8oi<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-frwm2xrksl<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-fj7gs031q6<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-fj42vucf99<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-z1qxl7s2zn<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-9m1zg8p5wc<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpr-show-sidebar<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-7seqacq2ol<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wpr-hash<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">persist:hs-beacon-message-44cc73fb-7636-4206-b115-c7b33823551b<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wistia-video-progress-09kolaz9o0<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">redux_current_tab<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">redux_current_tab_get<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">redux_current_tab_wtr_settings<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">web-vitals-extension-metrics<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">friends_with_mate<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_PREFERENCES_USER_2<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_2<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">pys_advanced_form_data<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ht_ctc_admin<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ht_ctc_storage<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">multiFbc<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">_gcl_ls<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp-autosave-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">topicsLastReferenceTime<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">mp_150605b3b9f979922f2ac5a52e2dcfe9_mixpanel<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">mp_gen_new_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">mp_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nom<\/h5>\n<\/div>\n<div class=\"name\">ezTOC_hidetoc-1<\/div>\n<div class=\"retention-header\">\n\t<h5>Caducitat<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funci\u00f3<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div>\n<h2>\u00bfQui\u00e9n utiliza las cookies en esta p\u00e1gina web?<\/h2>\n<p>La identificaci\u00f3n de qui\u00e9n utiliza las cookies, el tipo de cookies utilizadas y dem\u00e1s detalles, se indica a continuaci\u00f3n:<\/p>\n<ul>\n<li><a href=\"https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage?hl=es\" target=\"_blank\" rel=\"noopener\">Uso de las cookies de Google Analytics en los sitios web<\/a>.<\/li>\n<li><a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener\">Condiciones de privacidad de Google Analytics<\/a>.<\/li>\n<li><a href=\"http:\/\/www.google.com\/policies\/technologies\/types\/\" target=\"_blank\" rel=\"noopener\">Condiciones de las cookies de Google<\/a>.<\/li>\n<li><a href=\"https:\/\/privacy.console.didomi.io\/\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de privacidad de Didomi<\/a><\/li>\n<li><a href=\"https:\/\/privacy.didomi.io\/en\/\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de cookies de Didomi<\/a><\/li>\n<\/ul>\n<p>Complianz GDPR\/CCPA Cookie Consent es el programa encargado de la realizaci\u00f3n del an\u00e1lisis de cookies, perteneciente a Diadomi.<\/p>\n<h2>Servicios de terceros<\/h2>\n<p>Adicionalmente, nombre del titular tiene presencia en portales y servicios de terceros para los que, si se desea conocer las condiciones de privacidad y uso de cookies, deber\u00e1n consultarle las pol\u00edticas proporcionadas por los mismos:<\/p>\n<ul>\n<li><a href=\"http:\/\/instagram.com\/clinicasden\/\" target=\"_blank\" rel=\"nofollow noopener\">Instagram<\/a><\/li>\n<li>Facebook<\/li>\n<li><a href=\"https:\/\/www.linkedin.com\/company\/clinicas-den\/about\/\" target=\"_blank\" rel=\"nofollow noopener\">Linkedin<\/a><\/li>\n<li><a href=\"https:\/\/www.youtube.com\/channel\/UC-paZZ1NTfz_-A6fWIem0Ew\" target=\"_blank\" rel=\"nofollow noopener\">YouTube<\/a><\/li>\n<\/ul>\n<h2>Aceptaci\u00f3n de la pol\u00edtica de cookies<\/h2>\n<p>El titular del website muestra informaci\u00f3n sobre su Pol\u00edtica de cookies en la parte inferior\u00a0de cualquier p\u00e1gina del portal con cada inicio de sesi\u00f3n con el objeto de que usted sea consciente.Ante esta informaci\u00f3n es posible llevar a cabo las siguientes acciones:<\/p>\n<ul>\n<li><strong>Aceptar cookies<\/strong>. No se volver\u00e1 a visualizar este aviso al acceder a cualquier p\u00e1gina del portal durante la presente sesi\u00f3n.<\/li>\n<li><strong>Modificar la configuraci\u00f3n<\/strong>. Podr\u00e1 obtener m\u00e1s informaci\u00f3n sobre qu\u00e9 son las cookies, conocer la Pol\u00edtica de cookies del website. y modificar la configuraci\u00f3n de su navegador para restringir o bloquear las cookies del website en cualquier momento. En el caso de restringir o bloquear las cookies puede ver reducidas las funcionalidades de la web.<\/li>\n<\/ul>\n<p><strong>Nota:<\/strong> Las cookies de tipo \u201cPropias\u201d son utilizadas s\u00f3lo por el propietario de esta web y las cookies \u201cDe terceros\u201d son utilizadas, tambi\u00e9n, por el prestador del servicio que est\u00e1 detallado la tabla anterior.<\/p>\n<p>Puede informarse de las transferencias a terceros pa\u00edses que, en su caso, realizan los terceros identificados en esta pol\u00edtica de cookies en sus correspondientes pol\u00edticas.<\/p>\n<h2>\u00bfC\u00f3mo puedo desactivar o eliminar estas cookies?<\/h2>\n<p>Puede usted permitir o bloquear las cookies, as\u00ed como borrar sus datos de navegaci\u00f3n (incluidas las cookies) desde el navegador que usted utiliza. Consulte las opciones e instrucciones que ofrece su navegador para ello. Tenga en cuenta que, si acepta las cookies de terceros, deber\u00e1 eliminarlas desde las opciones del navegador.<\/p>\n<p>A continuaci\u00f3n, se indica c\u00f3mo realizar estas configuraciones en los diferentes navegadores:<\/p>\n<ul>\n<li><a href=\"https:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-sitios-web-rastrear-preferencias?redirectslug=habilitar-y-deshabilitar-cookies-que-los-sitios-we&amp;redirectlocale=es\" target=\"_blank\" rel=\"noopener\">Firefox<\/a>.<\/li>\n<li><a href=\"http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=es&amp;answer=95647\" target=\"_blank\" rel=\"noopener\">Chrome<\/a>.<\/li>\n<li><a href=\"https:\/\/support.microsoft.com\/es-es\/topic\/c%C3%B3mo-eliminar-archivos-de-cookies-en-internet-explorer-bca9446f-d873-78de-77ba-d42645fa52fc\" target=\"_blank\" rel=\"noopener\">Internet Explorer<\/a>.<\/li>\n<li><a href=\"https:\/\/support.microsoft.com\/es-es\/microsoft-edge\/eliminar-las-cookies-en-microsoft-edge-63947406-40ac-c3b8-57b9-2a946a29ae09\" target=\"_blank\" rel=\"noopener\">Microsoft Edge<\/a>.<\/li>\n<li><a href=\"https:\/\/support.apple.com\/es-es\/guide\/safari\/sfri11471\/mac\" target=\"_blank\" rel=\"noopener\">Safari<\/a>.<\/li>\n<li><a href=\"https:\/\/help.opera.com\/en\/latest\/web-preferences\/#cookies\" target=\"_blank\" rel=\"noopener\">Opera<\/a>.<\/li>\n<li>Otros navegadores: consulte la documentaci\u00f3n del navegador que tenga instalado.<\/li>\n<\/ul>\n<h2>Complemento de inhabilitaci\u00f3n para navegadores de Google Analytics<\/h2>\n<p>Si desea rechazar las cookies anal\u00edticas de Google Analytics en todos los navegadores, de forma que no se env\u00ede informaci\u00f3n suya a Google Analytics, puede descargar un complemento que realiza esta funci\u00f3n desde <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\" target=\"_blank\" rel=\"noopener\">este enlace<\/a>.<\/p>\n<h2>Ejercicio de derechos<\/h2>\n<p>Puede conocer y ejercer sus derechos en materia de protecci\u00f3n de datos accediendo a nuestra <a href=\"\/politica-privacidad\/\" target=\"_blank\" rel=\"noopener\">pol\u00edtica de privacidad<\/a>.[\/vc_column_text][vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_single_image image=\u00bb2741&#8243; img_size=\u00bbfull\u00bb alignment=\u00bbcenter\u00bb qode_css_animation=\u00bb\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbgrid\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb z_index=\u00bb\u00bb][vc_column][vc_empty_space height=\u00bb50px\u00bb][vc_column_text] Pol\u00edtica de Cookies [\/vc_column_text][vc_empty_space height=\u00bb50px\u00bb][vc_column_text]En cumplimiento con lo dispuesto en el art\u00edculo 22.2 de la Ley 34\/2002, de 11 de julio, de Servicios de&#8230;<\/p>\n","protected":false},"author":3,"featured_media":2206,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-10397","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/clinicasden.com\/ca\/wp-json\/wp\/v2\/pages\/10397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinicasden.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinicasden.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinicasden.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/clinicasden.com\/ca\/wp-json\/wp\/v2\/comments?post=10397"}],"version-history":[{"count":5,"href":"https:\/\/clinicasden.com\/ca\/wp-json\/wp\/v2\/pages\/10397\/revisions"}],"predecessor-version":[{"id":11854,"href":"https:\/\/clinicasden.com\/ca\/wp-json\/wp\/v2\/pages\/10397\/revisions\/11854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clinicasden.com\/ca\/wp-json\/wp\/v2\/media\/2206"}],"wp:attachment":[{"href":"https:\/\/clinicasden.com\/ca\/wp-json\/wp\/v2\/media?parent=10397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}